{"id":9777,"date":"2024-06-14T10:37:00","date_gmt":"2024-06-14T20:37:00","guid":{"rendered":"https:\/\/hawaiipublicschools.org\/?p=9777"},"modified":"2025-09-29T18:43:39","modified_gmt":"2025-09-30T04:43:39","slug":"2024-hidoe-releases-summary-report-on-rebuild-plan-for-king-kamehameha-iii-elementary","status":"publish","type":"post","link":"https:\/\/hawaiipublicschools.org\/es\/2024-hidoe-releases-summary-report-on-rebuild-plan-for-king-kamehameha-iii-elementary\/","title":{"rendered":"HIDOE publica un informe resumido sobre el plan de reconstrucci\u00f3n de la escuela primaria King Kamehameha III"},"content":{"rendered":"<p>LAHAINA \u2013 El Departamento de Educaci\u00f3n del Estado de Haw\u00e1i (HIDOE) public\u00f3 hoy un informe que resume las aportaciones y opiniones de la comunidad en una serie de oportunidades para recibir comentarios sobre el plan de reconstrucci\u00f3n de la Escuela Primaria King Kamehameha III. Un total de 291 miembros de la comunidad, incluyendo profesores y personal, familias de la escuela, exalumnos y miembros interesados de la comunidad, completaron encuestas de opini\u00f3n, realizadas en tres formatos: en una reuni\u00f3n de profesores y personal, en una reuni\u00f3n comunitaria abierta o en l\u00ednea.&nbsp;<\/p>\n\n\n\n<p>La Escuela Primaria King Kamehameha III fue uno de los sitios destruidos por el incendio forestal que arras\u00f3 Lahaina en agosto de 2023, desplazando a estudiantes, familias, profesores y personal de un entorno de aprendizaje que hab\u00eda funcionado en Front Street durante m\u00e1s de un siglo. HIDOE est\u00e1 actualmente en proceso de identificar una ubicaci\u00f3n permanente para reconstruir la escuela, que actualmente opera en una ubicaci\u00f3n temporal en 100 Akahele St, Lahaina, HI 96761.<\/p>\n\n\n\n<p>\u201cEl Departamento ha estado en conversaciones con el condado sobre la infraestructura necesaria para los terrenos que se est\u00e1n considerando para un campus permanente de la Escuela Primaria King Kamehameha III\u201d, declar\u00f3 Rebecca Winkie, Superintendente del \u00c1rea del Complejo H\u0101na-Lahainaluna-L\u0101na\u02bbi-Moloka\u02bbi. \u201cNos alienta el compromiso colectivo de las agencias colaboradoras de trabajar juntas para proporcionar un campus de reemplazo permanente para King Kamehameha III lo antes posible para servir a la comunidad de Lahaina\u201d.&nbsp;<\/p>\n\n\n\n<p>Las tres opciones presentadas a la comunidad fueron: la ubicaci\u00f3n original en Front Street; Pulelehua, cerca de la ubicaci\u00f3n temporal actual; y Ka\u02bbanapali 2020 \u2013 Pu\u02bbukoli\u02bbi Village Mauka. Para m\u00e1s informaci\u00f3n sobre las posibles ventajas y desventajas de cada sitio desde una perspectiva de planificaci\u00f3n, consulte el texto completo de&nbsp;<a href=\"\/es\/DOE%20Forms\/Maui\/KKIII%20Community%20Feedback%20Report.pdf\/\" target=\"_blank\" rel=\"noreferrer noopener\">el informe<\/a>.&nbsp;<\/p>\n\n\n\n<p>Los temas clave que surgieron a trav\u00e9s de la retroalimentaci\u00f3n incluyeron:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Preocupaciones culturales e hist\u00f3ricas: el deseo de mantener la ubicaci\u00f3n original o al menos elegir una ubicaci\u00f3n dentro de la ciudad de Lahaina para la escuela; preocupaci\u00f3n por lo que suceder\u00e1 con la ubicaci\u00f3n de Front Street si la escuela no se reconstruye all\u00ed; y consideraci\u00f3n por el significado hist\u00f3rico del nombre y la ubicaci\u00f3n de la escuela primaria King Kamehameha III.&nbsp;<\/li>\n\n\n\n<li>Proceso de toma de decisiones de HIDOE: parcialidad percibida hacia la ubicaci\u00f3n de Pulelehua; solicitudes para incluir m\u00e1s voces y miembros de la comunidad en el proceso de toma de decisiones; y solicitudes para priorizar a los estudiantes y a la comunidad por sobre la conveniencia y las finanzas.<\/li>\n\n\n\n<li>La importancia de planificar la reconstrucci\u00f3n y el crecimiento futuros: el deseo de la comunidad de construir dos escuelas en lugar de una; consideraciones sobre el tr\u00e1fico; mantener la cultura y el car\u00e1cter de Lahaina; vivienda general y para maestros al mismo tiempo; cuestiones de zonificaci\u00f3n y permisos; y brindar oportunidades educativas y extracurriculares para los estudiantes.<\/li>\n<\/ul>\n\n\n\n<p>De las tres opciones propuestas, los comentarios de los participantes se desglosaron de la siguiente manera:&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"\/PublishingImages\/5-CONNECT\/8-MEDIAROOM\/KK3%20Community%20Feedback%201.png\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Calle delantera<\/strong><br><strong>Ubicaci\u00f3n original&nbsp;<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"\/PublishingImages\/5-CONNECT\/8-MEDIAROOM\/KK3%20Community%20Feedback%202.png\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Pulelehua<\/strong><br><strong>Cerca de la ubicaci\u00f3n temporal actual<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"\/PublishingImages\/5-CONNECT\/8-MEDIAROOM\/KK3%20Community%20Feedback%204.png\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Ka&#039;anapali 2020<\/strong><br><strong>Pueblo Pu\u02bbukoli\u02bbi Mauka<\/strong><a href=\"\/es\/PublishingImages\/5-CONNECT\/8-MEDIAROOM\/KK3%20Community%20Feedback%204.png\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a>&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Los siguientes fueron citados como los factores m\u00e1s influyentes para los participantes:&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"\/PublishingImages\/5-CONNECT\/8-MEDIAROOM\/KK3%20Community%20Feedback%203.png\" alt=\"\"\/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Historia y tradici\u00f3n \u2013 29.6%<\/li>\n\n\n\n<li>Conveniencia de ubicaci\u00f3n \u2013 16.1%<\/li>\n\n\n\n<li>Conveniencia \u2013 14.4%<\/li>\n\n\n\n<li>Capacidad de expansi\u00f3n \u2013 13.2%<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Costo de construcci\u00f3n: 11,81 TP3T<\/li>\n\n\n\n<li>Distancia desde la zona quemada \u2013 9.9%<\/li>\n\n\n\n<li>Otros \u2013 5.0%<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<p>HIDOE solicit\u00f3 la opini\u00f3n de la escuela y la comunidad local mediante dos reuniones presenciales el 21 de mayo: una para el profesorado y el personal, y otra para las familias de la escuela y el p\u00fablico. Posteriormente, se compartieron las grabaciones de las reuniones y se realiz\u00f3 una encuesta en l\u00ednea para que los miembros de la comunidad pudieran compartir su opini\u00f3n, incluso si no pudieron asistir a los eventos presenciales. El Departamento contrat\u00f3 a Pa\u02bbakai Communications para facilitar las reuniones como tercero neutral y ayudar en la recopilaci\u00f3n y el an\u00e1lisis de la opini\u00f3n.<\/p>\n\n\n\n<p>Los comentarios de la comunidad incluidos en este informe est\u00e1n actualmente bajo revisi\u00f3n cuidadosa por parte del liderazgo de HIDOE y jugar\u00e1n un papel importante en la definici\u00f3n de los pr\u00f3ximos pasos para el proceso de selecci\u00f3n del sitio.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>LAHAINA \u2013 The Hawai\u02bbi State Department of Education (HIDOE) today released a report summarizing input and opinions from a series of community feedback opportunities on the rebuild plan for King Kamehameha III Elementary School. A total of 291 community members including faculty\/staff, current school family members, alumni, and interested community members completed feedback surveys, delivered [&hellip;]<\/p>","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","wp_popup_display_lightbox":0,"wp_popup_suppress":"","wp_popup_trigger":"","wp_popup_trigger_amount":0,"wp_popup_disable_on_mobile":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-9777","post","type-post","status-publish","format-standard","hentry","category-news"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","taxonomy_info":{"category":[{"value":21,"label":"News"}]},"featured_image_src_large":false,"author_info":{"display_name":"Chanel Honda","author_link":"https:\/\/hawaiipublicschools.org\/es\/author\/chanel-hondak12-hi-us\/"},"comment_info":0,"category_info":[{"term_id":21,"name":"News","slug":"news","term_group":0,"term_taxonomy_id":21,"taxonomy":"category","description":"","parent":0,"count":322,"filter":"raw","cat_ID":21,"category_count":322,"category_description":"","cat_name":"News","category_nicename":"news","category_parent":0}],"tag_info":false,"publishpress_future_action":{"enabled":false,"date":"2026-05-19 17:04:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"post_status","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/posts\/9777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/comments?post=9777"}],"version-history":[{"count":0,"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/posts\/9777\/revisions"}],"wp:attachment":[{"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/media?parent=9777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/categories?post=9777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hawaiipublicschools.org\/es\/wp-json\/wp\/v2\/tags?post=9777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}